{"id":157060,"date":"2023-01-16T08:12:12","date_gmt":"2023-01-16T08:12:12","guid":{"rendered":"https:\/\/www.leeb-balkone.com\/de\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/"},"modified":"2023-01-16T08:12:12","modified_gmt":"2023-01-16T08:12:12","slug":"die-sieben-wichtigsten-qualitaetskriterien-beim-balkon","status":"publish","type":"post","link":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/","title":{"rendered":"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon"},"content":{"rendered":"<header class=\"wp-block-group alignfull t3-header u-max-wide t3-header-text has-white-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n    <div class=\"wp-block-group o-grid u-md-1 u-sm-1 is-layout-flow wp-block-group-is-layout-flow\">\n  <div class=\"wp-block-group u-g-10 u-g-s-2\">\n      <div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/www.leeb-balkone.com\/at\/\">Home<\/a><\/span><\/span><\/div>\n      \n    <h1>Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon<\/h1>\n  <\/div>\n<\/div>\n  <\/header>\n\n\n\n\n\n\n\n<section class=\"wp-block-cgb-t3-section-block alignfull b-pt-small b-pb-none is-style-bg-white\" style=\"display:inherit;min-height:inherit\">\n<div class=\"wp-block-cgb-t3-container-block none\" style=\"background-color:none\"><div class=\"grid-container\"><div class=\"grid-x\"><div class=\"cell small-12 medium-9 large-0 medium-offset-1 b-has-lsmb\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-1024x684.jpg\" alt=\"balkongelaender alu vision lofer blog\" class=\"wp-image-112353\" srcset=\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-1024x684.jpg 1024w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-300x200.jpg 300w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-768x513.jpg 768w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-1536x1025.jpg 1536w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Leeb Balkon &#8211; Kombination aus Glas und Aluminium-Designelemten<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Balkone, Loggien und Terrassen sind immer ein Gewinn: An Wohn- und Freiraum und an Lebensqualit\u00e4t! Aber wie stellt man sicher, dass man \u00fcber viele Jahre hinweg Freude an seinem Wohnungsau\u00dfenbereich hat und diesen tats\u00e4chlich nutzt? Die Antwort lautet: Setzen Sie beim Balkon auf bew\u00e4hrte Qualit\u00e4t.<\/p>\n\n\n\n<p>Was genau diese Qualit\u00e4t ausmacht, ist allerdings weniger leicht zu beantworten. Wegen der Vielfalt der Balkone sind auch deren konstruktive Bauart und das Spektrum an verwendeten Baustoffen gro\u00df. Dennoch gibt es <strong>eine Reihe von Kriterien<\/strong>, die <strong>als Qualit\u00e4tsmerkmale<\/strong> herangezogen werden k\u00f6nnen. Und es gibt <strong>Entscheidungshilfen<\/strong>, die Sie dabei unterst\u00fctzen, aus der Vielzahl an Balkonanbietern jene herauszufiltern, die f\u00fcr echte Handschlagqualit\u00e4t und Verl\u00e4sslichkeit stehen.<\/p>\n\n\n\n<p>Als Richtschnur hier die sieben wichtigsten Qualit\u00e4tsmerkmale, die Sie bei Ihrer Auswahl ber\u00fccksichtigen sollten:<\/p>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-cgb-t3-container-block none\" style=\"background-color:none\"><div class=\"grid-container\"><div class=\"grid-x\"><div class=\"cell small-12 medium-9 large-0 medium-offset-1 b-has-lsmb\">\n<h2 class=\"wp-block-heading\" id=\"kriterium-1\">Kriterium Nr. 1: Technisch einwandfreie Konstruktion<\/h2>\n\n\n\n<p>Balkone sind Wind und Wetter oft intensiv ausgesetzt und damit eine <strong>potenziell kritische W\u00e4rmebr\u00fccke<\/strong>. Umso wichtiger ist ein <strong>technisch einwandfreier Balkonanschluss<\/strong>, der Feuchtigkeitsprobleme von vornherein verhindert. Denn W\u00e4rmebr\u00fccken verursachen nicht nur Energieverluste. Sie k\u00f6nnen langfristig zu Sch\u00e4den in der Bausubstanz f\u00fchren, die nur mit viel Aufwand und hohen Kosten zu beseitigen sind. Wer diese Tatsache vernachl\u00e4ssigt, holt sich mit dem Balkon unter Umst\u00e4nden ein echtes Problembauteil ans Haus.<\/p>\n\n\n\n<p>Daher gilt: Egal ob Balkonsanierung oder Neubau \u2013 <strong>erfahrene<\/strong> und <strong>speziell ausgebildete<\/strong> <strong>Unternehmen<\/strong> wie <strong>Leeb Balkone<\/strong> wissen, wie man technisch einwandfreie Konstruktionen umsetzt. Von der <strong>w\u00e4rmebr\u00fcckenfreien Befestigung<\/strong> bis zur richtigen <strong>Entw\u00e4sserung<\/strong> haben sie alle Details im Blick. Fragen Sie ruhig genau nach. Vermeintliche Kleinigkeiten wie <strong>schr\u00e4g gestellte Blumenk\u00e4stenb\u00f6den<\/strong>, die ein konstantes Ablaufen des Wassers garantieren, <strong>hinterl\u00fcftete Bauteile<\/strong>, ein <strong>Handlauf mit integriertem Wasserschutz<\/strong> oder <strong>abgeschr\u00e4gte Einbundlatten<\/strong>, die auch an schwer zug\u00e4nglichen Stellen dauerhafte Feuchtigkeit vermeiden, machen in Summe die Qualit\u00e4t eines Balkons aus.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-1024x684.jpg\" alt=\"balkongelaender alu barcelona blog\" class=\"wp-image-112301\" style=\"width:937px;height:626px\" srcset=\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-1024x684.jpg 1024w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-300x200.jpg 300w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-768x513.jpg 768w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-1536x1025.jpg 1536w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-barcelona-blog-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Leeb Balkon aus Aluminium mit Designelementen<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-2\">Kriterium Nr. 2: Langlebigkeit durch hochwertige Materialien<\/h2>\n\n\n\n<p>\u00dcber die Ausf\u00fchrungsart Ihres Balkons entscheidet allein der Geschmack. Doch egal ob <strong>Glas<\/strong>, <strong>Aluminium oder Holz<\/strong> \u2013 <strong>hochwertige Fertigungsmaterialien<\/strong> sind der <strong>Schl\u00fcssel zu langfristigem Wohngl\u00fcck <\/strong>am Balkon. Speziell bei <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/balkongelaender\/balkongelaender-holz\/\">Holzbalkonen<\/a><\/strong> entscheidet neben der Holzart der <strong>professionelle Umgang<\/strong> mit diesem <strong>Naturmaterial<\/strong> \u00fcber die dauerhaft sch\u00f6ne Optik, Formstabilit\u00e4t und Lebensdauer. Aus diesem Grund empfehlen wir beim Balkongel\u00e4nder <strong>Nadelh\u00f6lzer<\/strong>, die m\u00f6glichst langsam gewachsen sind. Diese sind <strong>haltbarer<\/strong>, <strong>verziehen sich nicht<\/strong> und neigen <strong>weniger<\/strong> zu <strong>Rissen<\/strong>. Bei Leeb Balkone werden die sorgsam ausgew\u00e4hlten Holzst\u00e4mme au\u00dferdem naturbelassen luftgetrocknet, bevor sie in den Trocknungsanlagen weiterverarbeitet werden und ein <strong>spezielles Impr\u00e4gnierungsverfahren<\/strong> durchlaufen.<\/p>\n\n\n\n<p>Trotzdem: In der Kosten-Nutzen-Rechnung muss man bei Holz auch den sp\u00e4teren Pflegeaufwand einkalkulieren. Langfristig gesehen ist daher <strong>Aluminium<\/strong> eine echte Alternative. Wenn dennoch nicht auf die Optik von Holz verzichten m\u00f6chte, kann beispielsweise bei Leeb zwischen 13 t\u00e4uschend echt aussehenden <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/balkongelaender\/balkongelaender-alu\/\">Aluminumbalkone<\/a> in Holzoptik<\/strong> w\u00e4hlen.<em> <\/em>Wie man hier gute Qualit\u00e4t erkennt? Unter anderem an der <strong>Beschichtung<\/strong> des Aluminiums, das eine kratzfeste und wasserabweisende Oberfl\u00e4che sicherstellt. Je h\u00e4rter die Legierung, desto h\u00f6her die Festigkeit und damit der Schutz vor Hagel und anderen mechanischen Einfl\u00fcssen. Eine schmutzabweisende Pulverbeschichtung wiederum sorgt daf\u00fcr, dass das Gel\u00e4nder auch nach vielen Jahren genauso sch\u00f6n aussieht wie am ersten Tag. Das zuk\u00fcnftige Streichen kann man also getrost streichen.<\/p>\n\n\n\n<p>Wer sich f\u00fcr einen <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/balkongelaender\/balkongelaender-glas\/\">Glasbalkon<\/a><\/strong> entscheidet, sollte in jedem Fall zu Echtglas greifen. H\u00f6chste Sicherheit garantiert dabei <strong>VSG-Sicherheitsglas<\/strong>. Dieses besteht aus zwei \u00fcbereinander liegenden Glasscheiben, die mit einer rei\u00dffesten und elastischen Folie verklebt sind. Sollte tats\u00e4chlich durch einen Schlag eine der beiden Glasscheiben zu Schaden kommen, bleibt die zweite Scheibe durch die Folie intakt.<\/p>\n\n\n\n<p>Bei der Qualit\u00e4t all dieser \u201eGrundmaterialien\u201c k\u00f6nnen viele Hersteller \u00fcberzeugen. Die Spreu vom Weizen trennt sich aber sp\u00e4testens, wenn Sie nach <strong>Verarbeitungsdetails<\/strong> fragen. Als echte Qualit\u00e4tskriterien gelten beispielsweise <strong>verdeckte Verschraubungen<\/strong>. Sie sorgen daf\u00fcr, dass kein Makel die \u00c4sthetik st\u00f6rt \u2013 weder auf der Innen- noch auf der Au\u00dfenseite. <strong>Softline-Kanten<\/strong> sind an den Kanten st\u00e4rker beschichtet und sorgen so f\u00fcr mehr Stabilit\u00e4t.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-1024x684.jpg\" alt=\"balkongelaender alu vision blog\" class=\"wp-image-112306\" style=\"width:930px;height:621px\" srcset=\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-1024x684.jpg 1024w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-300x200.jpg 300w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-768x513.jpg 768w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-1536x1025.jpg 1536w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-blog-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Leeb Balkon aus Glas mit Softline-Kanten<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-3\">Kriterium Nr. 3: Fertigungsstandards &amp; Sicherheit<\/h2>\n\n\n\n<p>Nach der Wahl der Materialien entscheiden im n\u00e4chsten Schritt die <strong>Fertigungsprozesse<\/strong> \u00fcber die Qualit\u00e4t Ihres Balkons. Da Sie in den meisten F\u00e4llen kaum die Chance haben werden, in die Produktionshallen Ihres in Frage kommenden Anbieters zu blicken, hier ein paar Tipps, wie Sie trotzdem seine Arbeitsweise und Verl\u00e4sslichkeit beurteilen k\u00f6nnen.<\/p>\n\n\n\n<p>Gehen Sie in einem ersten Schritt auf die Website Ihres m\u00f6glichen Balkonlieferanten. Diese sagt in den meisten F\u00e4llen schon sehr viel \u00fcber die Professionalit\u00e4t aus. Finden Sie viele Referenzprojekte? Sehr gut! Schauen Sie au\u00dferdem nach, ob der Anbieter nach bestimmten <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/ueber-leeb\/zertifizierte-qualitaet\/\">Qualit\u00e4tsnormen<\/a><\/strong> (beispielsweise ISO 9001) zertifiziert ist. Gleiches gilt f\u00fcr die Produkte, die er anbietet. Beide Zertifikate stehen f\u00fcr <strong>permanente und unabh\u00e4ngige Qualit\u00e4tskontrollen<\/strong>, die der Betrieb durchl\u00e4uft. <strong>Auszeichnungen<\/strong> oder <strong>Qualit\u00e4tssiegel<\/strong> sind ebenfalls ein klares Zeichen daf\u00fcr, dass bei diesem Hersteller nach bestem Wissen und Gewissen gearbeitet wird.<\/p>\n\n\n\n<p><strong>Tipp: <\/strong>Bez\u00fcglich eines Blicks hinter die Kulissen gibt es lobenswerte Ausnahmen. Der Balkonhersteller <strong>Leeb Balkone<\/strong> etwa erm\u00f6glicht seinen Kunden Werksf\u00fchrungen und steht dabei gerne Rede und Antwort. &nbsp;<\/p>\n\n\n\n<p>Ein weiteres Argument daf\u00fcr, beim Neubau oder der Sanierung des Balkons auf einen Fachmann zu h\u00f6ren, ist das Thema <strong>Sicherheit<\/strong>. Denn Balkongel\u00e4nder haben neben ihrer \u00e4sthetischen Funktion in erster Linie die Aufgabe, als <strong>Absturzsicherung<\/strong> zu dienen. Sie m\u00fcssen bestimmten Belastungen standhalten und d\u00fcrfen nicht erklimmbar sein. Daher wird Ihnen jeder professionelle Balkonanbieter von gew\u00f6hnlichen Zaun-Elementen als Absturzsicherung dringend abraten. Mehr noch: Er wei\u00df \u00fcber <strong>Mindesth\u00f6hen<\/strong> oder den erlaubten <strong>Abstand zwischen den St\u00e4ben<\/strong> genau Bescheid.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-4\">Kriterium Nr. 4: Umweltschutz &amp; Nachhaltigkeit<\/h2>\n\n\n\n<p>Das Thema Nachhaltigkeit gewinnt nicht nur in der Gesellschaft insgesamt, sondern auch bei immer mehr Bauherren an Bedeutung. Sie stellen sich Fragen wie: Wie umweltfreundlich sind die Baustoffe, die zur Verwendung kommen? Wie kann ich aktiv zum Klimaschutz beitragen und unn\u00f6tige Transporte verhindern?<\/p>\n\n\n\n<p>Wer bei der Auswahl seines Balkons auf Umweltschutz Wert legt, sollte sich folgende Kriterien genau ansehen: Woher kommt das <strong>Holz<\/strong>, sollten Sie einen Holzbalkon bevorzugen? Kommt dieses <strong>aus heimischen W\u00e4ldern?<\/strong> <strong>Welche Transportwege<\/strong> hat es hinter sich, bevor es \u00fcberhaupt verarbeitet wird?<\/p>\n\n\n\n<p>In der Verarbeitung selbst spielt beim Thema Umweltschutz die <strong>Oberfl\u00e4chenbehandlung<\/strong> eine gro\u00dfe Rolle \u2013 sowohl was die verwendeten Inhaltsstoffe als auch den <strong>Energieverbrauch<\/strong> dieses Bearbeitungsschritts betrifft. Leeb Balkone hat deshalb ein innovatives Verfahren zur <strong>umweltfreundlichen Pulverbeschichtung<\/strong> von Aluminium entwickelt. Diese sorgt f\u00fcr eine kratzfeste, witterungsbest\u00e4ndige Oberfl\u00e4che, sodass das Wasser samt Schmutz durch den Lotuseffekt besser abperlt. Das Besondere dabei: Die Pulverbeschichtung erfolgt mittels chromfreiem No-Rinse Verfahren. Vereinfacht ausgedr\u00fcckt handelt es sich dabei um ein stetiges Kreislaufsystem, das den Verlust von s\u00e4mtlichen Prozessw\u00e4ssern verhindert und komplett abwasserfrei funktioniert.<\/p>\n\n\n\n<p>Am Produktionsstandort von Leeb wird das Thema <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/ueber-leeb\/nachhaltigkeit-bei-leeb\/\">Nachhaltigkeit<\/a><\/strong> aber auch im Bereich Energiegewinnung und -nutzung gro\u00dfgeschrieben. Rund zwei Drittel unseres j\u00e4hrlichen Strombedarfs deckt man hier durch eine rund 3.500 m\u00b2 gro\u00dfe Photovoltaikanlage auf den D\u00e4chern der Produktionshallen. Das spart j\u00e4hrlich rund 325.000 kg CO\u00b2. Geheizt wird in den Leeb B\u00fcros und Fertigungshallen \u00fcber das firmeninterne Biomasseheizwerk, das \u00fcber 1 Megawatt (1 Mio. Watt!) Leistung verf\u00fcgt. Auch die notwendige Prozessw\u00e4rme f\u00fcr die Pulverbeschichtung wird vom Biomasseheizwerk erzeugt, in dem vorwiegend eigene Holzabf\u00e4lle aus der laufenden Produktion sowie regionale Biomasse von Landwirten aus der Umgebung verheizt werden.<\/p>\n\n\n\n<p>Wer sich mit dem Thema Nachhaltigkeit besch\u00e4ftigt, wei\u00df aber auch: Den <strong>CO2-Fu\u00dfabdruck<\/strong> eines Produktes muss man sich immer <strong>\u00fcber seinen gesamten Lebenszyklus<\/strong> hinweg ansehen. So gesehen macht es Sinn, auf einen oberfl\u00e4chenbehandelten Balkon zu setzen, der eine <strong>lange Haltbarkeit<\/strong> und <strong>dauerhafte Sch\u00f6nheit<\/strong> garantiert.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-1024x682.jpg\" alt=\"firmenzentrale photovoltaik nachhaltigkeit blog\" class=\"wp-image-112316\" style=\"width:922px;height:613px\" srcset=\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-1024x682.jpg 1024w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-300x200.jpg 300w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-768x512.jpg 768w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-1536x1023.jpg 1536w, https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/firmenzentrale-photovoltaik-nachhaltigkeit-blog-2048x1364.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Firmenzentrale Leeb Balkone mit Photovoltaikanlage auf D\u00e4chern<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-5\">Kriterium Nr. 5: Erfahrung &amp; Innovationswillen<\/h2>\n\n\n\n<p>Haben Sie ein paar Anbieter in die engere Auswahl genommen, sollten Sie in einem n\u00e4chsten Schritt zwei Dinge in Ihre Entscheidung einflie\u00dfen lassen: Die <strong>Erfahrung<\/strong> und die <strong>Innovationskraft <\/strong>Ihres Balkon-Profis. Wie man diese ausmacht? Zum einen finden Sie auf der Website bestimmt Referenzbeispiele, vielleicht sogar ein paar Kundenstimmen. Je mehr \u201eBest Practice\u201c-Beispiele hergezeigt werden, desto besser. Wenn Vorher-Nachher-Situationen bildlich festgehalten wurden, bekommen Sie einen noch besseren Einblick in die Arbeit Ihres m\u00f6glichen Anbieters.<\/p>\n\n\n\n<p>Doch Erfahrung allein ist nicht alles. Die Materialien, aber auch die Architektur und damit die Kundenw\u00fcnsche sind einem st\u00e4ndigen Wandel unterworfen. Achten Sie deshalb darauf, ob Ihr Anbieter <strong>mit der Zeit geht <\/strong>und wirklich Erfahrung in der Balkon-Kategorie mitbringt, die Sie sich w\u00fcnschen.<\/p>\n\n\n\n<p>Bestes Beispiel f\u00fcr die erfolgreiche Kombination beider Schl\u00fcsselkriterien ist der Balkonhersteller <strong>Leeb Balkone<\/strong>. Als Europas Nr. 1 bei Balkonen und Z\u00e4unen mit mehr als 150.000 Kunden in vielen L\u00e4ndern findet man auf der Website des erfahrenen Experten unz\u00e4hlige Referenzen, zufriedenen Kundenstimmen und anschauliches Bildmaterial \u00fcber die gro\u00dfe Bandbreite an Angeboten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-6\">Kriterium Nr. 6: Rund-um-Service<\/h2>\n\n\n\n<p>Die <strong>Qualit\u00e4t<\/strong> eines Balkons kann einerseits an <strong>handfesten technischen Kriterien<\/strong> festgemacht werden. Andererseits werden Sie nur dann eine echte Freude mit Ihrem \u201eOutdoor-Wohnzimmer\u201c haben, wenn dieses <strong>individuell an Ihre Bed\u00fcrfnisse angepasst<\/strong> ist.<\/p>\n\n\n\n<p>Bevor Sie in die Umsetzung gehen, h\u00f6ren Sie daher beim Gespr\u00e4ch mit dem Balkonanbieter genau hin: Fragt er konkret nach Ihren Wohnw\u00fcnschen und Vorstellungen? Nach den genauen Gegebenheiten vor Ort? Oder geht es nur um sein Leistungsspektrum?<\/p>\n\n\n\n<p>Vergessen Sie nicht: Die sp\u00e4tere Qualit\u00e4t Ihres Balkons ist stark von <strong><a href=\"https:\/\/www.leeb-balkone.com\/at\/service\/planungsservice\/\">Beratungs- und Planungsqualit\u00e4t<\/a> <\/strong>Ihres Anbieters abh\u00e4ngig. Schlie\u00dflich gleicht kein Bauprojekt dem anderen. So vielf\u00e4ltig die Anforderungen der Auftraggeber, so unterschiedlich ist auch die Planung und Umsetzung. Vertrauen Sie daher lieber einem Balkonbauer wie Leeb, der in der Lage ist, von der erstklassigen Beratung bis zur Montage vor Ort <strong>alles aus einer Hand<\/strong> zu \u00fcbernehmen. Woran Sie das erkennen? Neben der Qualit\u00e4t des Erstgespr\u00e4chs an den vorhandenen <strong>Planungstools<\/strong> wie digitalem Fotomontage-Service, der <strong>Kreativit\u00e4t<\/strong>, die er in der Planung einbringt, der <strong>Vielfalt des Sortiments<\/strong> und der <strong>Anzahl an Referenzprojekten<\/strong>, die er vorweisen kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"kriterium-7\">Kriterium Nr. 7: Preis-Leistungsverh\u00e4ltnis<\/h2>\n\n\n\n<p>Der <strong>Preis<\/strong> ist letztlich <strong>nur ein Kriterium von vielen<\/strong>, auf das Sie Ihr Augenmerk legen sollten. Denn je nach Balkongr\u00f6\u00dfe, Material des Gel\u00e4nders, Montageart und eventuellen statischen Gutachten bei einer Sanierung k\u00f6nnen die <strong>Kosten stark variieren<\/strong>. <em><s><\/s><\/em><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-cgb-t3-container-block none\" style=\"background-color:none\"><div class=\"grid-container\"><div class=\"grid-x\"><div class=\"cell small-12 medium-9 large-0 medium-offset-1 b-has-lsmb\">\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<p>Jeder Balkon schafft ein Mehr an Lebensqualit\u00e4t und geh\u00f6rt heute f\u00fcr viele einfach dazu. Doch als <strong>sensible Schnittstelle zwischen Innen und Au\u00dfen<\/strong> sollten Sie bei der Umsetzung auf die Erfahrung und das Know-how eines <strong>echten Fachmannes<\/strong> h\u00f6ren. Das sorgt nicht nur f\u00fcr <strong>mehr Freude<\/strong>, sondern auch f\u00fcr <strong>mehr Sicherheit<\/strong> und <strong>Langlebigkeit<\/strong>.<\/p>\n\n\n\n<p>Wer auf Qualit\u00e4t Wert legt, darf daher bei den Kostenvoranschl\u00e4gen nicht nur die einzelnen Posten und das, was unter\u2018m Strich herauskommt, miteinander vergleichen. Fragen Sie genau nach, wodurch sich die einzelnen <strong>Materialien<\/strong> auszeichnen, wie in der <strong>Fertigung und Montage<\/strong> h\u00f6chste Qualit\u00e4t sichergestellt wird, wie viel <strong>Erfahrung<\/strong> Ihr Anbieter mitbringt und achten Sie schon im Erstgespr\u00e4ch darauf, wie detailliert er Ihre <strong>pers\u00f6nlichen W\u00fcnsche<\/strong> und die <strong>bestehenden Rahmenbedingungen<\/strong> hinterfragt. Wer all diese Kriterien im Hinterkopf beh\u00e4lt, wird garantiert einen verl\u00e4sslichen Partner finden.<\/p>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hier die sieben wichtigsten Qualit\u00e4tsmerkmale beim Balkon!<\/p>\n","protected":false},"author":3,"featured_media":112313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"template-onepager.blade.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[162,155,163],"tags":[],"post_folder":[],"class_list":["post-157060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-balkonbau-mit-leeb","category-nachhaltigkeit-oekologie","category-technik-innovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sieben Qualit\u00e4tskriterien beim Balkon - Leeb Balkone \u00d6sterreich<\/title>\n<meta name=\"description\" content=\"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon\" \/>\n<meta property=\"og:description\" content=\"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\" \/>\n<meta property=\"og:site_name\" content=\"Leeb Balkone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/balkone\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-16T08:12:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-1024x684.jpg\" \/>\n<meta name=\"author\" content=\"jbacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\"},\"author\":{\"name\":\"jbacher\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/person\/15f1f398efcf4703721e46c2136421fa\"},\"headline\":\"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon\",\"datePublished\":\"2023-01-16T08:12:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\"},\"wordCount\":1874,\"publisher\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg\",\"articleSection\":[\"Balkonbau mit Leeb\",\"Nachhaltigkeit &amp; \u00d6kologie\",\"Technik &amp; Innovation\"],\"inLanguage\":\"de-AT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\",\"url\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\",\"name\":\"Sieben Qualit\u00e4tskriterien beim Balkon - Leeb Balkone\",\"isPartOf\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg\",\"datePublished\":\"2023-01-16T08:12:12+00:00\",\"description\":\"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage\",\"url\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg\",\"contentUrl\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leeb-balkone.com\/at\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#website\",\"url\":\"https:\/\/www.leeb-balkone.com\/at\/\",\"name\":\"Leeb Balkone\",\"description\":\"Balkone und Z\u00e4une\",\"publisher\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leeb-balkone.com\/at\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#organization\",\"name\":\"Leeb Balkone \u00d6sterreich\",\"url\":\"https:\/\/www.leeb-balkone.com\/at\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2020\/11\/leeb-logo.svg\",\"contentUrl\":\"https:\/\/www.leeb-balkone.com\/app\/uploads\/2020\/11\/leeb-logo.svg\",\"width\":741,\"height\":204,\"caption\":\"Leeb Balkone Gmbh\"},\"image\":{\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/balkone\/\",\"https:\/\/www.instagram.com\/leeb_balkone\/\",\"https:\/\/www.youtube.com\/channel\/UCIthPeoOLCeQZjGnyJ3myTg\",\"https:\/\/www.linkedin.com\/company\/leeb-balkone\/\",\"https:\/\/www.pinterest.com\/leeb_balkone\/\",\"https:\/\/www.tiktok.com\/@leeb.balkone\",\"https:\/\/oesterreichwiki.org\/wiki\/Leeb_Balkone\",\"https:\/\/de.wikipedia.org\/wiki\/Gnesau\"],\"legalName\":\"Leeb Balkone GmbH\",\"alternateName\":\"Leeb Balkone\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/person\/15f1f398efcf4703721e46c2136421fa\",\"name\":\"jbacher\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sieben Qualit\u00e4tskriterien beim Balkon - Leeb Balkone \u00d6sterreich","description":"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon","og_description":"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!","og_url":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/","og_site_name":"Leeb Balkone","article_publisher":"https:\/\/www.facebook.com\/balkone\/","article_published_time":"2023-01-16T08:12:12+00:00","og_image":[{"url":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-2-1024x684.jpg","type":"","width":"","height":""}],"author":"jbacher","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#article","isPartOf":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/"},"author":{"name":"jbacher","@id":"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/person\/15f1f398efcf4703721e46c2136421fa"},"headline":"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon","datePublished":"2023-01-16T08:12:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/"},"wordCount":1874,"publisher":{"@id":"https:\/\/www.leeb-balkone.com\/at\/#organization"},"image":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg","articleSection":["Balkonbau mit Leeb","Nachhaltigkeit &amp; \u00d6kologie","Technik &amp; Innovation"],"inLanguage":"de-AT"},{"@type":"WebPage","@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/","url":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/","name":"Sieben Qualit\u00e4tskriterien beim Balkon - Leeb Balkone","isPartOf":{"@id":"https:\/\/www.leeb-balkone.com\/at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage"},"image":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg","datePublished":"2023-01-16T08:12:12+00:00","description":"Setzen Sie bei Ihrem Balkon auf bew\u00e4hrte Qualit\u00e4t und achten Sie bei der Auswahl auf diese sieben Qualit\u00e4tsmerkmale!","breadcrumb":{"@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#primaryimage","url":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg","contentUrl":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2023\/01\/balkongelaender-alu-vision-lofer-blog-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/www.leeb-balkone.com\/at\/blog\/die-sieben-wichtigsten-qualitaetskriterien-beim-balkon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leeb-balkone.com\/at\/"},{"@type":"ListItem","position":2,"name":"Die sieben wichtigsten Qualit\u00e4tskriterien beim Balkon"}]},{"@type":"WebSite","@id":"https:\/\/www.leeb-balkone.com\/at\/#website","url":"https:\/\/www.leeb-balkone.com\/at\/","name":"Leeb Balkone","description":"Balkone und Z\u00e4une","publisher":{"@id":"https:\/\/www.leeb-balkone.com\/at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leeb-balkone.com\/at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/www.leeb-balkone.com\/at\/#organization","name":"Leeb Balkone \u00d6sterreich","url":"https:\/\/www.leeb-balkone.com\/at\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/logo\/image\/","url":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2020\/11\/leeb-logo.svg","contentUrl":"https:\/\/www.leeb-balkone.com\/app\/uploads\/2020\/11\/leeb-logo.svg","width":741,"height":204,"caption":"Leeb Balkone Gmbh"},"image":{"@id":"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/balkone\/","https:\/\/www.instagram.com\/leeb_balkone\/","https:\/\/www.youtube.com\/channel\/UCIthPeoOLCeQZjGnyJ3myTg","https:\/\/www.linkedin.com\/company\/leeb-balkone\/","https:\/\/www.pinterest.com\/leeb_balkone\/","https:\/\/www.tiktok.com\/@leeb.balkone","https:\/\/oesterreichwiki.org\/wiki\/Leeb_Balkone","https:\/\/de.wikipedia.org\/wiki\/Gnesau"],"legalName":"Leeb Balkone GmbH","alternateName":"Leeb Balkone"},{"@type":"Person","@id":"https:\/\/www.leeb-balkone.com\/at\/#\/schema\/person\/15f1f398efcf4703721e46c2136421fa","name":"jbacher"}]}},"_links":{"self":[{"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/posts\/157060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/comments?post=157060"}],"version-history":[{"count":0,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/posts\/157060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/media\/112313"}],"wp:attachment":[{"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/media?parent=157060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/categories?post=157060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/tags?post=157060"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.leeb-balkone.com\/at\/wp-json\/wp\/v2\/post_folder?post=157060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}